{"id":67,"date":"2020-02-04T10:37:56","date_gmt":"2020-02-04T01:37:56","guid":{"rendered":"http:\/\/ikiiki-med.seki-dev.com\/wp\/?page_id=67"},"modified":"2020-04-02T19:33:39","modified_gmt":"2020-04-02T10:33:39","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/","title":{"rendered":"\u304a\u554f\u3044\u5408\u308f\u305b"},"content":{"rendered":"<h2>\u304a\u554f\u3044\u5408\u308f\u305b\u306f\u3053\u3061\u3089<\/h2>\n<p>\u5f53\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u4f1a\u3078\u306e\u304a\u554f\u3044\u5408\u308f\u305b\u306f\u3001\u4e0b\u8a18\u30e1\u30fc\u30eb\u30d5\u30a9\u30fc\u30e0\u3092\u3054\u5229\u7528\u4e0b\u3055\u3044\u3002<br \/>\u5f53\u4f1a\u304b\u3089\u5dee\u3057\u4e0a\u3052\u305f\u304a\u8fd4\u4e8b\u304c\u5c4a\u304b\u306a\u3044\u4e8b\u4f8b\u304c\u591a\u767a\u3057\u3066\u3044\u307e\u3059\u3002<br \/>\u304a\u8fd4\u4e8b\u3092\u5e0c\u671b\u3055\u308c\u308b\u5834\u5408\u306f\u3001m.ehime-u.ac.jp\u3001ehime-u.ac.jp \u304b\u3089\u306e\u30e1\u30fc\u30eb\u3092\u53d7\u4fe1\u3067\u304d\u308b\u3088\u3046\u306b\u8a2d\u5b9a\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n<h4>\u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u533b\u7642\u30b5\u30fc\u30d3\u30b9\u8ab2<\/h4>\n<figure class=\"wp-block-table\">\n<table>\n<tbody>\n<tr>\n<th>TEL<\/th>\n<td><a href=\"http:\/\/089-960-5099\/\">089-960-5099<\/a><\/td>\n<\/tr>\n<tr>\n<th>e-mail<\/th>\n<td><a href=\"mailto:ikiiki@m.ehime-u.ac.jp\">ikiiki@m.ehime-u.ac.jp<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u304a\u554f\u3044\u5408\u308f\u305b\u306f\u3053\u3061\u3089 \u5f53\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u4f1a\u3078\u306e\u304a\u554f\u3044\u5408\u308f\u305b\u306f\u3001\u4e0b\u8a18\u30e1\u30fc\u30eb\u30d5\u30a9\u30fc\u30e0\u3092\u3054\u5229\u7528\u4e0b\u3055\u3044\u3002\u5f53\u4f1a\u304b\u3089\u5dee\u3057\u4e0a\u3052\u305f\u304a\u8fd4\u4e8b\u304c\u5c4a\u304b\u306a\u3044\u4e8b\u4f8b\u304c\u591a\u767a\u3057\u3066\u3044\u307e\u3059\u3002\u304a\u8fd4\u4e8b\u3092\u5e0c\u671b\u3055\u308c\u308b\u5834\u5408\u306f\u3001m.ehime-u.ac.jp\u3001ehime-u [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":580,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-67","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662\u3000\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a | Just another WordPress site\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u304a\u554f\u3044\u5408\u308f\u305b | \u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662 \u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-04T01:37:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-04-02T10:33:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u304a\u554f\u3044\u5408\u308f\u305b | \u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662 \u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#listItem\",\"name\":\"\\u304a\\u554f\\u3044\\u5408\\u308f\\u305b\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#listItem\",\"position\":2,\"name\":\"\\u304a\\u554f\\u3044\\u5408\\u308f\\u305b\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/#organization\",\"name\":\"\\u611b\\u5a9b\\u5927\\u5b66\\u533b\\u5b66\\u90e8\\u9644\\u5c5e\\u75c5\\u9662\\u3000\\u30dc\\u30e9\\u30f3\\u30c6\\u30a3\\u30a2\\u3044\\u304d\\u3044\\u304d\\u4f1a\",\"description\":\"Just another WordPress site\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#webpage\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/\",\"name\":\"\\u304a\\u554f\\u3044\\u5408\\u308f\\u305b | \\u611b\\u5a9b\\u5927\\u5b66\\u533b\\u5b66\\u90e8\\u9644\\u5c5e\\u75c5\\u9662 \\u30dc\\u30e9\\u30f3\\u30c6\\u30a3\\u30a2\\u3044\\u304d\\u3044\\u304d\\u4f1a\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/5-700x200-1.png\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#mainImage\",\"width\":700,\"height\":200},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/contact\\\/#mainImage\"},\"datePublished\":\"2020-02-04T10:37:56+09:00\",\"dateModified\":\"2020-04-02T19:33:39+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/#website\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/\",\"name\":\"\\u611b\\u5a9b\\u5927\\u5b66\\u533b\\u5b66\\u90e8\\u9644\\u5c5e\\u75c5\\u9662\\u3000\\u30dc\\u30e9\\u30f3\\u30c6\\u30a3\\u30a2\\u3044\\u304d\\u3044\\u304d\\u4f1a\",\"description\":\"Just another WordPress site\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/hospital\\\/volunteer\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u304a\u554f\u3044\u5408\u308f\u305b | \u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662 \u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a","description":"","canonical_url":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer#listItem","position":1,"name":"Home","item":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer","nextItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#listItem","name":"\u304a\u554f\u3044\u5408\u308f\u305b"}},{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#listItem","position":2,"name":"\u304a\u554f\u3044\u5408\u308f\u305b","previousItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/#organization","name":"\u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662\u3000\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a","description":"Just another WordPress site","url":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/"},{"@type":"WebPage","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#webpage","url":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/","name":"\u304a\u554f\u3044\u5408\u308f\u305b | \u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662 \u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a","inLanguage":"ja","isPartOf":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/#website"},"breadcrumb":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-content\/uploads\/2020\/04\/5-700x200-1.png","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#mainImage","width":700,"height":200},"primaryImageOfPage":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/#mainImage"},"datePublished":"2020-02-04T10:37:56+09:00","dateModified":"2020-04-02T19:33:39+09:00"},{"@type":"WebSite","@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/#website","url":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/","name":"\u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662\u3000\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a","description":"Just another WordPress site","inLanguage":"ja","publisher":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/#organization"}}]},"og:locale":"ja_JP","og:site_name":"\u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662\u3000\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a | Just another WordPress site","og:type":"article","og:title":"\u304a\u554f\u3044\u5408\u308f\u305b | \u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662 \u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a","og:url":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/","article:published_time":"2020-02-04T01:37:56+00:00","article:modified_time":"2020-04-02T10:33:39+00:00","twitter:card":"summary","twitter:title":"\u304a\u554f\u3044\u5408\u308f\u305b | \u611b\u5a9b\u5927\u5b66\u533b\u5b66\u90e8\u9644\u5c5e\u75c5\u9662 \u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3044\u304d\u3044\u304d\u4f1a"},"aioseo_meta_data":{"post_id":"67","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 01:50:32","updated":"2026-08-26 00:57:49","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u304a\u554f\u3044\u5408\u308f\u305b\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer"},{"label":"\u304a\u554f\u3044\u5408\u308f\u305b","link":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/contact\/"}],"_links":{"self":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/pages\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":3,"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/pages\/67\/revisions"}],"predecessor-version":[{"id":661,"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/pages\/67\/revisions\/661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/media\/580"}],"wp:attachment":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/hospital\/volunteer\/wp-json\/wp\/v2\/media?parent=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}