{"id":6310,"date":"2022-12-23T11:46:59","date_gmt":"2022-12-23T02:46:59","guid":{"rendered":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/?p=6310"},"modified":"2022-12-23T11:46:59","modified_gmt":"2022-12-23T02:46:59","slug":"%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a%e9%96%8b%e5%82%ac%e3%81%ae%e3%81%94%e6%a1%88%e5%86%85","status":"publish","type":"post","link":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/","title":{"rendered":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185"},"content":{"rendered":"<p style=\"text-align: justify; text-justify: inter-ideograph; vertical-align: baseline; margin: 12.0pt 0mm 12.0pt 0mm;\"><span style=\"font-family: '\u6e38\u660e\u671d Light',serif; color: #101010; letter-spacing: .5pt;\">\u6765\u308b\u3001<span lang=\"EN-US\">2023<\/span>\u5e74<span lang=\"EN-US\">1<\/span>\u6708<span lang=\"EN-US\">21<\/span>\u65e5\uff08\u571f\u66dc\uff09\u306b\u3001\u57ce\u6238\u8f1d\u4ec1\u6559\u6388\u5927\u4f1a\u9577\u306e\u3082\u3068\u3001<span lang=\"EN-US\">ANA<\/span>\u30af\u30e9\u30a6\u30f3\u30d7\u30e9\u30b6\u30db\u30c6\u30eb\u677e\u5c71\u306b\u3066\u3001<\/span><\/p>\n<p style=\"text-align: justify; text-justify: inter-ideograph; vertical-align: baseline; font-stretch: inherit; line-height: inherit; margin: 12.0pt 0mm 12.0pt 0mm;\"><span style=\"font-family: '\u6e38\u660e\u671d Light',serif; color: #101010; letter-spacing: .5pt;\">\u7b2c<span lang=\"EN-US\">96<\/span>\u56de\u65e5\u672c\u5fc3\u81d3\u8840\u7ba1\u653e\u5c04\u7dda\u7814\u7a76\u4f1a\u304c\u958b\u50ac\u3055\u308c\u307e\u3059\u3002\u591a\u304f\u306e\u5148\u751f\u65b9\u306e\u53c2\u52a0\u3092\u304a\u5f85\u3061\u3057\u3066\u304a\u308a\u307e\u3059\u3002<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>\u25a0\u958b\u50ac\u540d<br \/>\n\u7b2c96\u56de\u65e5\u672c\u5fc3\u81d3\u8840\u7ba1\u653e\u5c04\u7dda\u7814\u7a76\u4f1a<\/p>\n<p><a href=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2022\/12\/dai96_housyasen13331.pdf\">\u3010\u30d1\u30f3\u30d5\u30ec\u30c3\u30c8\u3011<\/a><\/p>\n<p><a href=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2022\/12\/\u6821\u6b631219_WEB\u7528\u30d7\u30ed\u30b0\u30e9\u30e0143431.pdf\">\u3010\u30d7\u30ed\u30b0\u30e9\u30e0\u3011<\/a><\/p>\n<p>\u25a0\u958b\u50ac\u65e5\u7a0b<br \/>\n2023\u5e741\u670821\u65e5\uff08\u571f\u66dc\uff099:30\u301c18:00<\/p>\n<p>\u25a0\u958b\u50ac\u4f1a\u5834<br \/>\nANA\u30af\u30e9\u30a6\u30f3\u30d7\u30e9\u30b6\u30db\u30c6\u30eb\u677e\u5c71\u3000\u672c\u99284\u968e\u300c\u30c0\u30a4\u30e4\u30e2\u30f3\u30c9\u30dc\u30fc\u30eb\u30eb\u30fc\u30e0\u300d<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"loaV2p3yZ4\"><p><a href=\"https:\/\/www.anacpmatsuyama.com\/\">TOP\u30da\u30fc\u30b8<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;TOP\u30da\u30fc\u30b8&#8221; &#8212; ANA\u30af\u30e9\u30a6\u30f3\u30d7\u30e9\u30b6\u30db\u30c6\u30eb\u677e\u5c71\" src=\"https:\/\/www.anacpmatsuyama.com\/embed\/#?secret=loaV2p3yZ4\" data-secret=\"loaV2p3yZ4\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><br \/>\n\u3012790-8520\u3000\u611b\u5a9b\u770c\u677e\u5c71\u5e02\u4e00\u756a\u753a3-2-1 TEL: 089-933-5511<\/p>\n<p>&nbsp;<\/p>\n<p>\u25c6\u53c2\u52a0\u767b\u9332\u3000\u4ee5\u4e0bURL\u304b\u3089\u304a\u5165\u308a\u304f\u3060\u3055\u3044\u3002<\/p>\n<p><a href=\"https:\/\/con-system.com\/jscvr\/\">https:\/\/con-system.com\/jscvr\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u6765\u308b\u30012023\u5e741\u670821\u65e5\uff08\u571f\u66dc\uff09\u306b\u3001\u57ce\u6238\u8f1d\u4ec1\u6559\u6388\u5927\u4f1a\u9577\u306e\u3082\u3068\u3001ANA\u30af\u30e9\u30a6\u30f3\u30d7\u30e9\u30b6\u30db\u30c6\u30eb\u677e\u5c71\u306b\u3066\u3001 \u7b2c96\u56de\u65e5\u672c\u5fc3\u81d3\u8840\u7ba1\u653e\u5c04\u7dda\u7814\u7a76\u4f1a\u304c\u958b\u50ac\u3055\u308c\u307e\u3059\u3002\u591a\u304f\u306e\u5148\u751f\u65b9\u306e\u53c2\u52a0\u3092\u304a\u5f85\u3061\u3057\u3066\u304a\u308a\u307e\u3059\u3002 &nbsp; \u25a0\u958b\u50ac\u540d \u7b2c9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,15,10],"tags":[],"class_list":["post-6310","post","type-post","status-publish","format-standard","hentry","category-11","category-15","category-10"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2020\/12\/ogimage.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2020\/12\/ogimage.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-23T02:46:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-23T02:46:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2020\/12\/ogimage.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#article\",\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\\u958b\\u50ac\\u306e\\u3054\\u6848\\u5185 | \\u611b\\u5a9b\\u5927\\u5b66\\u5927\\u5b66\\u9662\\u533b\\u5b66\\u7cfb\\u7814\\u7a76\\u79d1\\u653e\\u5c04\\u7dda\\u533b\\u5b66\",\"headline\":\"\\u95a2\\u9023\\u5b66\\u4f1a\\u958b\\u50ac\\u306e\\u3054\\u6848\\u5185\",\"author\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/#organization\"},\"datePublished\":\"2022-12-23T11:46:59+09:00\",\"dateModified\":\"2022-12-23T11:46:59+09:00\",\"inLanguage\":\"ja\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#webpage\"},\"articleSection\":\"\\u304a\\u77e5\\u3089\\u305b, \\u65b0\\u7740\\u60c5\\u5831, \\u95a2\\u9023\\u5b66\\u4f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/#listItem\",\"name\":\"\\u65b0\\u7740\\u60c5\\u5831\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/#listItem\",\"position\":2,\"name\":\"\\u65b0\\u7740\\u60c5\\u5831\",\"item\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/#listItem\",\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/#listItem\",\"position\":3,\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\",\"item\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#listItem\",\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\\u958b\\u50ac\\u306e\\u3054\\u6848\\u5185\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/#listItem\",\"name\":\"\\u65b0\\u7740\\u60c5\\u5831\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#listItem\",\"position\":4,\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\\u958b\\u50ac\\u306e\\u3054\\u6848\\u5185\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/category\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/#listItem\",\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/#organization\",\"name\":\"\\u611b\\u5a9b\\u5927\\u5b66\\u5927\\u5b66\\u9662\\u533b\\u5b66\\u7cfb\\u7814\\u7a76\\u79d1\\u653e\\u5c04\\u7dda\\u533b\\u5b66\",\"description\":\"\\u611b\\u5a9b\\u5927\\u5b66\\u5927\\u5b66\\u9662\\u533b\\u5b66\\u7cfb\\u7814\\u7a76\\u79d1\\u653e\\u5c04\\u7dda\\u533b\\u5b66\\u306e\\u516c\\u5f0f\\u30db\\u30fc\\u30e0\\u30da\\u30fc\\u30b8\\u3067\\u3059\\u3002\\u65b0\\u305f\\u306a\\u6280\\u8853\\u53ca\\u3073\\u64ae\\u50cf\\u88c5\\u7f6e\\u3092\\u7528\\u3044\\u305f\\u753b\\u50cf\\u8a3a\\u65ad\\u306b\\u95a2\\u3059\\u308b\\u7814\\u7a76\\u3092\\u884c\\u3063\\u3066\\u3044\\u307e\\u3059\\u3002\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/314e9f9e6041c2e1fbac19bebebe49477249219fb2244d5b15b4490a2229ebaf?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#webpage\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/\",\"name\":\"\\u95a2\\u9023\\u5b66\\u4f1a\\u958b\\u50ac\\u306e\\u3054\\u6848\\u5185 | \\u611b\\u5a9b\\u5927\\u5b66\\u5927\\u5b66\\u9662\\u533b\\u5b66\\u7cfb\\u7814\\u7a76\\u79d1\\u653e\\u5c04\\u7dda\\u533b\\u5b66\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\\\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\\\/6310\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-12-23T11:46:59+09:00\",\"dateModified\":\"2022-12-23T11:46:59+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/#website\",\"url\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/\",\"name\":\"\\u611b\\u5a9b\\u5927\\u5b66\\u5927\\u5b66\\u9662\\u533b\\u5b66\\u7cfb\\u7814\\u7a76\\u79d1\\u653e\\u5c04\\u7dda\\u533b\\u5b66\",\"description\":\"\\u611b\\u5a9b\\u5927\\u5b66\\u5927\\u5b66\\u9662\\u533b\\u5b66\\u7cfb\\u7814\\u7a76\\u79d1\\u653e\\u5c04\\u7dda\\u533b\\u5b66\\u306e\\u516c\\u5f0f\\u30db\\u30fc\\u30e0\\u30da\\u30fc\\u30b8\\u3067\\u3059\\u3002\\u65b0\\u305f\\u306a\\u6280\\u8853\\u53ca\\u3073\\u64ae\\u50cf\\u88c5\\u7f6e\\u3092\\u7528\\u3044\\u305f\\u753b\\u50cf\\u8a3a\\u65ad\\u306b\\u95a2\\u3059\\u308b\\u7814\\u7a76\\u3092\\u884c\\u3063\\u3066\\u3044\\u307e\\u3059\\u3002\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.m.ehime-u.ac.jp\\\/school\\\/radiology\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","description":"","canonical_url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#article","name":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","headline":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185","author":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/#organization"},"datePublished":"2022-12-23T11:46:59+09:00","dateModified":"2022-12-23T11:46:59+09:00","inLanguage":"ja","mainEntityOfPage":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#webpage"},"isPartOf":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#webpage"},"articleSection":"\u304a\u77e5\u3089\u305b, \u65b0\u7740\u60c5\u5831, \u95a2\u9023\u5b66\u4f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology#listItem","position":1,"name":"Home","item":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology","nextItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/#listItem","name":"\u65b0\u7740\u60c5\u5831"}},{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/#listItem","position":2,"name":"\u65b0\u7740\u60c5\u5831","item":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/#listItem","name":"\u95a2\u9023\u5b66\u4f1a"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/#listItem","position":3,"name":"\u95a2\u9023\u5b66\u4f1a","item":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#listItem","name":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/#listItem","name":"\u65b0\u7740\u60c5\u5831"}},{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#listItem","position":4,"name":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185","previousItem":{"@type":"ListItem","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/#listItem","name":"\u95a2\u9023\u5b66\u4f1a"}}]},{"@type":"Organization","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/#organization","name":"\u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","description":"\u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66\u306e\u516c\u5f0f\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u3059\u3002\u65b0\u305f\u306a\u6280\u8853\u53ca\u3073\u64ae\u50cf\u88c5\u7f6e\u3092\u7528\u3044\u305f\u753b\u50cf\u8a3a\u65ad\u306b\u95a2\u3059\u308b\u7814\u7a76\u3092\u884c\u3063\u3066\u3044\u307e\u3059\u3002","url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/"},{"@type":"Person","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/author\/admin\/#author","url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/314e9f9e6041c2e1fbac19bebebe49477249219fb2244d5b15b4490a2229ebaf?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#webpage","url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/","name":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","inLanguage":"ja","isPartOf":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/#website"},"breadcrumb":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/#breadcrumblist"},"author":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/author\/admin\/#author"},"datePublished":"2022-12-23T11:46:59+09:00","dateModified":"2022-12-23T11:46:59+09:00"},{"@type":"WebSite","@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/#website","url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/","name":"\u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","description":"\u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66\u306e\u516c\u5f0f\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u3059\u3002\u65b0\u305f\u306a\u6280\u8853\u53ca\u3073\u64ae\u50cf\u88c5\u7f6e\u3092\u7528\u3044\u305f\u753b\u50cf\u8a3a\u65ad\u306b\u95a2\u3059\u308b\u7814\u7a76\u3092\u884c\u3063\u3066\u3044\u307e\u3059\u3002","inLanguage":"ja","publisher":{"@id":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/#organization"}}]},"og:locale":"ja_JP","og:site_name":"\u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","og:type":"article","og:title":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","og:url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/","og:image":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2020\/12\/ogimage.png","og:image:secure_url":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2020\/12\/ogimage.png","og:image:width":1200,"og:image:height":630,"article:published_time":"2022-12-23T02:46:59+00:00","article:modified_time":"2022-12-23T02:46:59+00:00","twitter:card":"summary","twitter:title":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185 | \u611b\u5a9b\u5927\u5b66\u5927\u5b66\u9662\u533b\u5b66\u7cfb\u7814\u7a76\u79d1\u653e\u5c04\u7dda\u533b\u5b66","twitter:image":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wordpress\/wp-content\/uploads\/2020\/12\/ogimage.png"},"aioseo_meta_data":{"post_id":"6310","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-12-23 01:28:30","updated":"2025-06-04 00:48:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/\" title=\"\u65b0\u7740\u60c5\u5831\">\u65b0\u7740\u60c5\u5831<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/\" title=\"\u95a2\u9023\u5b66\u4f1a\">\u95a2\u9023\u5b66\u4f1a<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology"},{"label":"\u65b0\u7740\u60c5\u5831","link":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/"},{"label":"\u95a2\u9023\u5b66\u4f1a","link":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/category\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/"},{"label":"\u95a2\u9023\u5b66\u4f1a\u958b\u50ac\u306e\u3054\u6848\u5185","link":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/%e6%96%b0%e7%9d%80%e6%83%85%e5%a0%b1\/%e9%96%a2%e9%80%a3%e5%ad%a6%e4%bc%9a\/6310\/"}],"_links":{"self":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/posts\/6310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/comments?post=6310"}],"version-history":[{"count":5,"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/posts\/6310\/revisions"}],"predecessor-version":[{"id":6315,"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/posts\/6310\/revisions\/6315"}],"wp:attachment":[{"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/media?parent=6310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/categories?post=6310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.m.ehime-u.ac.jp\/school\/radiology\/wp-json\/wp\/v2\/tags?post=6310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}